{"id":5501,"date":"2025-05-18T18:39:04","date_gmt":"2025-05-18T18:39:04","guid":{"rendered":"https:\/\/verbo-encarnado-ssvm-abusos.info\/il-terzordine-dellistituto-del-verbo-incarnato-e-il-rifiuto-dei-genitori-quando-i-figli-escono\/"},"modified":"2025-05-21T04:41:47","modified_gmt":"2025-05-21T04:41:47","slug":"il-terzordine-dellistituto-del-verbo-incarnato-e-il-rifiuto-dei-genitori-quando-i-figli-escono","status":"publish","type":"post","link":"https:\/\/verbo-encarnado-ssvm-abusos.info\/it\/il-terzordine-dellistituto-del-verbo-incarnato-e-il-rifiuto-dei-genitori-quando-i-figli-escono\/","title":{"rendered":"Il Terz&#8217;Ordine dell&#8217;Istituto del Verbo Incarnato e il rifiuto dei genitori quando i figli &#8220;escono&#8221;"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Il Terz&#8217;Ordine dell&#8217;Istituto del Verbo Incarnato (IVE) riunisce laici che seguono una spiritualit\u00e0 piuttosto diffusa e senza una gerarchia ben definita. Molti di questi laici sono padri e madri di sacerdoti e religiosi sia dell&#8217;IVE che dei Servi del Signore e della Vergine di Matar\u00e1 (SSVM). Infatti, c&#8217;\u00e8 quasi automaticamente l&#8217;iscrizione dei padri e delle madri dei membri dell&#8217;IVE a questo Terz&#8217;Ordine. A differenza di altri Terzi Ordini pi\u00f9 tradizionali, sembra che non ci sia un registro formale dei membri o processi organizzativi comuni, come l&#8217;elezione dei presidenti o dei segretari. Questa mancanza di struttura \u00e8 un&#8217;altra caratteristica del mamarrachismo tipico del buelismo.    <\/p>\n\n<!--more-->\n\n<h3 class=\"wp-block-heading\">Rifiuto da parte dei genitori: un fenomeno settario<\/h3>\n\n<p class=\"wp-block-paragraph\">Un grave fenomeno che si pu\u00f2 osservare in questo contesto \u00e8 il rifiuto che alcuni di questi genitori esercitano nei confronti dei propri figli e figlie quando decidono di abbandonare il sacerdozio o la vita religiosa. Questa reazione, lungi dall&#8217;essere una semplice delusione, implica un profondo rifiuto, riflesso di un forte settarismo che predomina in certi ambienti del Terz&#8217;Ordine. <\/p>\n\n<p class=\"wp-block-paragraph\">Un caso paradigmatico \u00e8 quello di una coppia di San Rafael, Mendoza \u2013 lui medico e lei madre \u2013 di altissima reputazione, una di quelle che Buela ha trasferito da Buenos Aires. Ebbero due figli sacerdoti destinati alle missioni all&#8217;estero. Entrambi i figli hanno deciso di lasciare il sacerdozio, il maggiore (J. &#8220;junior&#8221;) diversi anni fa. Il figlio pi\u00f9 giovane (lo chiameremo &#8220;Beniamino&#8221;) era chiaramente una persona che non era fatta per la vita sacerdotale; tuttavia, il Verbo incarnato gli ha fatto il lavaggio del cervello per entrare in seminario, e ha deciso di entrare in una sola settimana. Durante la sua permanenza nella congregazione, Benjamin ebbe una vita pi\u00f9 da laico che da religioso e sacerdote. Benjamin ha recentemente lasciato il sacerdozio ed \u00e8 recentemente tornato in Argentina accompagnato dalla sua compagna, e la sua famiglia, che un tempo era orgogliosa di lui, ora mostra a lui e alla sua compagna un silenzio che esprime il loro risentimento.     <\/p>\n\n<p class=\"wp-block-paragraph\">Un altro caso esemplare \u00e8 quello di due signore della provincia di Mendoza, cugine di primo grado ed entrambe ora ottuagenarie, che hanno avuto figlie nelle Serve del Signore e della Vergine di Matar\u00e1. Queste due donne, che prima erano come sorelle, hanno smesso di parlarsi quando una delle figlie ha deciso di lasciare la SSVM. La disgregazione della famiglia \u00e8 stata quasi totale, a dimostrazione di come il rifiuto possa fratturare anche le relazioni pi\u00f9 strette.  <\/p>\n\n<p class=\"wp-block-paragraph\">Un terzo caso \u00e8 quello della famiglia che chiameremo Arieugerrad. Il figlio maggiore di questa famiglia entr\u00f2 nel seminario IVE, per uscirne qualche anno dopo, quando era ancora seminarista. Per anni non ha ricevuto alcuna comunicazione dalla sua famiglia. Inoltre, una figlia di questa famiglia ha lasciato la vita contemplativa della SSVM per unirsi sentimentalmente a un sacerdote IVE, una situazione che ha generato anche notevoli tensioni familiari. Ancora oggi, i genitori non riescono a perdonare quella situazione.    <\/p>\n\n<p class=\"wp-block-paragraph\">Questo tipo di comportamento \u00e8 analogo a quello osservato nelle comunit\u00e0 musulmane dove anche le figlie che decidono di sposarsi al di fuori della loro comunit\u00e0 o con una persona non accettata dal padre o dal fratello maggiore subiscono un rifiuto totale. In entrambi i casi, la rigidit\u00e0 e il controllo sociale distruggono il legame fondamentale tra sangue e famiglia, generando un settarismo profondamente dannoso. <\/p>\n\n<h3 class=\"wp-block-heading\">Conseguenze e necessit\u00e0 di cambiamento<\/h3>\n\n<p class=\"wp-block-paragraph\">Il settarismo qui implica una rigidit\u00e0 dottrinale e sociale che considera l&#8217;abbandono del ministero o della vita religiosa come un tradimento o un fallimento imperdonabile, generando un ambiente di esclusione e disgregazione familiare che pu\u00f2 essere devastante.<\/p>\n\n<p class=\"wp-block-paragraph\">Questi casi mostrano l&#8217;urgenza di un cambiamento culturale all&#8217;interno del Terz&#8217;Ordine, che favorisca la comprensione, il rispetto e l&#8217;accompagnamento sincero, senza pregiudizi o esclusioni.<\/p>\n\n<p class=\"wp-block-paragraph\">Solo cos\u00ec sar\u00e0 possibile andare verso una comunit\u00e0 veramente fraterna e umana, lontana dal settarismo e dall&#8217;esclusione.<\/p>\n\n<p class=\"wp-block-paragraph\"><strong>Esortiamo i laici dell&#8217;IVE a svegliarsi e a reagire a questa realt\u00e0 che distrugge le famiglie e le vite, in modo che possano costruire una comunit\u00e0 pi\u00f9 umana, accogliente e libera.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il Terz&#8217;Ordine dell&#8217;Istituto del Verbo Incarnato (IVE) riunisce laici che seguono una spiritualit\u00e0 piuttosto diffusa e senza una gerarchia ben definita. Molti di questi laici sono padri e madri di sacerdoti e religiosi sia dell&#8217;IVE che dei Servi del Signore e della Vergine di Matar\u00e1 (SSVM). Infatti, c&#8217;\u00e8 quasi automaticamente l&#8217;iscrizione dei padri e delle [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":5445,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"jetpack_seo_schema_type":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[185,289],"tags":[305,548],"class_list":["post-5501","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-degli-amministratori","category-riflessione","tag-caratteristiche-delle-sette","tag-terzo-ordine"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/verbo-encarnado-ssvm-abusos.info\/wp-content\/uploads\/2025\/05\/ChatGPT-Image-May-18-2025-08_32_20-PM.png?fit=1536%2C1024&ssl=1","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/verbo-encarnado-ssvm-abusos.info\/it\/wp-json\/wp\/v2\/posts\/5501","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/verbo-encarnado-ssvm-abusos.info\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/verbo-encarnado-ssvm-abusos.info\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/verbo-encarnado-ssvm-abusos.info\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/verbo-encarnado-ssvm-abusos.info\/it\/wp-json\/wp\/v2\/comments?post=5501"}],"version-history":[{"count":1,"href":"https:\/\/verbo-encarnado-ssvm-abusos.info\/it\/wp-json\/wp\/v2\/posts\/5501\/revisions"}],"predecessor-version":[{"id":5502,"href":"https:\/\/verbo-encarnado-ssvm-abusos.info\/it\/wp-json\/wp\/v2\/posts\/5501\/revisions\/5502"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/verbo-encarnado-ssvm-abusos.info\/it\/wp-json\/wp\/v2\/media\/5445"}],"wp:attachment":[{"href":"https:\/\/verbo-encarnado-ssvm-abusos.info\/it\/wp-json\/wp\/v2\/media?parent=5501"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/verbo-encarnado-ssvm-abusos.info\/it\/wp-json\/wp\/v2\/categories?post=5501"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/verbo-encarnado-ssvm-abusos.info\/it\/wp-json\/wp\/v2\/tags?post=5501"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}