{"id":5874,"date":"2025-06-25T15:11:55","date_gmt":"2025-06-25T15:11:55","guid":{"rendered":"https:\/\/verbo-encarnado-ssvm-abusos.info\/papa-leone-xiv-ha-parlato-degli-abusi-sessuali-della-chiesa-in-peru-e-ha-riconosciuto-il-lavoro-dei-giornalisti\/"},"modified":"2025-07-19T18:03:35","modified_gmt":"2025-07-19T18:03:35","slug":"papa-leone-xiv-ha-parlato-degli-abusi-sessuali-della-chiesa-in-peru-e-ha-riconosciuto-il-lavoro-dei-giornalisti","status":"publish","type":"post","link":"https:\/\/verbo-encarnado-ssvm-abusos.info\/it\/papa-leone-xiv-ha-parlato-degli-abusi-sessuali-della-chiesa-in-peru-e-ha-riconosciuto-il-lavoro-dei-giornalisti\/","title":{"rendered":"Papa Leone XIV ha parlato degli abusi sessuali della Chiesa in Per\u00f9 e ha riconosciuto il lavoro dei giornalisti"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><em>Riproduciamo qui un articolo pubblicato da <a href=\"https:\/\/www.infobae.com\/peru\/2025\/06\/21\/el-papa-leon-xiv-hablo-de-los-abusos-sexuales-de-la-iglesia-en-el-peru-y-reconocio-el-trabajo-de-los-periodistas\/\" target=\"_blank\" rel=\"noreferrer noopener\">infobae<\/a> il 21 giugno 2025<\/em><\/p>\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/www.infobae.com\/peru\/2025\/06\/19\/papa-leon-xiv-autoriza-nueva-medida-en-el-vaticano-para-recolectar-donaciones-ante-poco-apoyo-de-los-fieles\/\" target=\"_blank\" rel=\"noreferrer noopener\">Papa Leone XIV<\/a> rivolse un messaggio forte ed emozionante ai giornalisti peruviani che hanno indagato e denunciato gli abusi commessi all&#8217;interno della Chiesa, sottolineando l&#8217;urgenza di radicare una cultura della prevenzione e della trasparenza in tutte le strutture ecclesiali. Il messaggio, letto a Lima il 20 giugno da monsignor Jordi Bertomeu, commissario apostolico per il <a href=\"https:\/\/www.infobae.com\/peru\/2025\/04\/14\/el-sodalicio-dejo-de-existir-con-dolor-y-obediencia-aceptamos-esta-decision-aprobada-por-el-papa-francisco\/\" target=\"_blank\" rel=\"noreferrer noopener\">caso Sodalitium<\/a>, ha segnato la chiusura della presentazione dello<strong> spettacolo teatrale del &#8220;Progetto Ugar&#8221;,<\/strong> ispirato alla vita e all&#8217;opera della giornalista <a href=\"https:\/\/www.infobae.com\/peru\/2025\/05\/12\/papa-leon-xiv-ilusiona-con-un-posible-regreso-al-peru-pronto-van-a-tener-noticias-mias\/\" target=\"_blank\" rel=\"noreferrer noopener\">Paola Ugaz<\/a>. <\/p>\n\n<!--more-->\n\n<p class=\"wp-block-paragraph\">Papa Leone XIV, a poco pi\u00f9 di un mese dall&#8217;inizio del suo pontificato, ha evocato con gratitudine i suoi quasi 40 anni di esperienza in Per\u00f9 e ha partecipato simbolicamente alla prima dell&#8217;opera che, secondo le sue parole, &#8220;d\u00e0 voce e volto a un dolore messo a tacere per troppo tempo&#8221;. <strong> Il Pontefice ha espresso il suo &#8220;profondo rispetto e gratitudine&#8221; a coloro che hanno perseverato nel denunciare gli abusi<\/strong>, anche quando sono stati ignorati, squalificati o perseguiti. &#8220;Voglio ringraziare coloro che hanno perseverato in questa causa, anche quando sono stati ignorati, squalificati o addirittura perseguitati giudizialmente&#8221;, ha detto il papa, secondo Vatican News.Jordi Bertomeu, commissario apostolico per il caso Sodalitium, ha letto un messaggio del papa. <\/p>\n\n<p class=\"wp-block-paragraph\"><strong>L&#8217;opera teatrale &#8220;Proyecto Ugaz&#8221; non \u00e8 solo un&#8217;opera teatrale, ma, nelle parole del papa, costituisce &#8220;memoria, denuncia e, soprattutto, un atto di giustizia&#8221;.  <\/strong>Attraverso la rappresentazione, le vittime della famiglia spirituale estinta del Sodalitium e i giornalisti che le hanno accompagnate con coraggio, pazienza e fedelt\u00e0 alla verit\u00e0, illuminano il volto ferito ma speranzoso della Chiesa. Il papa ha riconosciuto che la lotta dei giornalisti e delle vittime \u00e8 anche la lotta della Chiesa, che deve riconoscere la ferita inferta a tante persone tradite nella loro ricerca di consolazione spirituale. <a href=\"https:\/\/www.infobae.com\/peru\/2025\/06\/25\/papa-leon-xiv-se-conmueve-al-hablar-en-espanol-ante-seminaristas-y-desata-ovacion-en-basilica-de-san-pedro-no-tengan-miedo\/\" target=\"_blank\" rel=\"noreferrer noopener\"><\/a><\/p>\n\n<p class=\"wp-block-paragraph\">Il messaggio di Leone XIV includeva un riferimento alla lettera del suo predecessore,<a href=\"https:\/\/www.infobae.com\/economia\/2025\/06\/20\/un-informe-encargado-por-el-papa-francisco-propone-reformas-para-enfrentar-la-crisis-de-deuda-en-paises-como-la-argentina\/\" target=\"_blank\" rel=\"noreferrer noopener\"> Papa Francesco<\/a>, indirizzata al Popolo di Dio nell&#8217;agosto 2018. In quella lettera, Francesco sottolineava:<strong> &#8220;Il dolore delle vittime e delle loro famiglie \u00e8 anche il nostro dolore, e quindi \u00e8 urgente ribadire il nostro impegno a garantire la protezione dei minori e degli adulti vulnerabili&#8221;. <\/strong>Francesco ha anche distinto tra crimine e corruzione, e ha invitato a una profonda conversione ecclesiale, intesa come cammino concreto di umilt\u00e0, verit\u00e0 e riparazione. <\/p>\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Riproduciamo qui un articolo pubblicato da infobae il 21 giugno 2025 Papa Leone XIV rivolse un messaggio forte ed emozionante ai giornalisti peruviani che hanno indagato e denunciato gli abusi commessi all&#8217;interno della Chiesa, sottolineando l&#8217;urgenza di radicare una cultura della prevenzione e della trasparenza in tutte le strutture ecclesiali. Il messaggio, letto a Lima [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":5813,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"jetpack_seo_schema_type":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[182],"tags":[318,563,562],"class_list":["post-5874","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie","tag-abusi-sessuali","tag-leone-xiv","tag-papa-leone"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/verbo-encarnado-ssvm-abusos.info\/wp-content\/uploads\/2025\/06\/3VY7EVGRIZHFTABWG64J5KFRQQ.avif","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/verbo-encarnado-ssvm-abusos.info\/it\/wp-json\/wp\/v2\/posts\/5874","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/verbo-encarnado-ssvm-abusos.info\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/verbo-encarnado-ssvm-abusos.info\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/verbo-encarnado-ssvm-abusos.info\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/verbo-encarnado-ssvm-abusos.info\/it\/wp-json\/wp\/v2\/comments?post=5874"}],"version-history":[{"count":1,"href":"https:\/\/verbo-encarnado-ssvm-abusos.info\/it\/wp-json\/wp\/v2\/posts\/5874\/revisions"}],"predecessor-version":[{"id":5875,"href":"https:\/\/verbo-encarnado-ssvm-abusos.info\/it\/wp-json\/wp\/v2\/posts\/5874\/revisions\/5875"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/verbo-encarnado-ssvm-abusos.info\/it\/wp-json\/wp\/v2\/media\/5813"}],"wp:attachment":[{"href":"https:\/\/verbo-encarnado-ssvm-abusos.info\/it\/wp-json\/wp\/v2\/media?parent=5874"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/verbo-encarnado-ssvm-abusos.info\/it\/wp-json\/wp\/v2\/categories?post=5874"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/verbo-encarnado-ssvm-abusos.info\/it\/wp-json\/wp\/v2\/tags?post=5874"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}