{"id":6200,"date":"2025-08-21T16:11:20","date_gmt":"2025-08-21T16:11:20","guid":{"rendered":"https:\/\/verbo-encarnado-ssvm-abusos.info\/caso-anthony-del-castillo-finalmente-uma-declaracao-oficial-da-diocese-de-la-rochelle\/"},"modified":"2025-08-21T16:17:27","modified_gmt":"2025-08-21T16:17:27","slug":"caso-anthony-del-castillo-finalmente-uma-declaracao-oficial-da-diocese-de-la-rochelle","status":"publish","type":"post","link":"https:\/\/verbo-encarnado-ssvm-abusos.info\/pt-br\/caso-anthony-del-castillo-finalmente-uma-declaracao-oficial-da-diocese-de-la-rochelle\/","title":{"rendered":"Caso Anthony del Castillo: finalmente uma declara\u00e7\u00e3o oficial da diocese de La Rochelle!"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>A diocese de La Rochelle (no departamento de Charente-Maritime, Fran\u00e7a) cedeu \u00e0 press\u00e3o da m\u00eddia e finalmente emitiu uma declara\u00e7\u00e3o oficial sobre o padre Anthony del Castillo, mais de um m\u00eas ap\u00f3s nossa publica\u00e7\u00e3o!<\/strong><\/p>\n\n<p class=\"wp-block-paragraph\"><strong>Por outro lado, para ter uma publica\u00e7\u00e3o oficial do Instituto do Verbo Encarnado, teremos que esperar, e esperar, e esperar&#8230;<\/strong><\/p>\n\n<p class=\"wp-block-paragraph\">O texto do comunicado de imprensa abaixo:<\/p>\n\n<p class=\"wp-block-paragraph\"><em>Hoje, 20 de agosto de 2025, o site &#8220;Catholic Response&#8221; publicou uma declara\u00e7\u00e3o implicando um padre do Instituto do Verbo Encarnado, padre Anthony Del Castillo, por suspeita de abuso de poder que levou a rela\u00e7\u00f5es sexuais com uma jovem de 18 anos potencialmente vulner\u00e1vel.<\/em><\/p>\n\n<!--more-->\n\n<p class=\"wp-block-paragraph\"><em>Os fatos relatados s\u00e3o em sua maioria precisos e o padre Del Castillo os reconheceu.<\/em><\/p>\n\n<p class=\"wp-block-paragraph\"><em>Por outro lado, a diocese e o instituto n\u00e3o ficaram inativos e n\u00e3o tentaram escond\u00ea-los, mas recentemente tomamos conhecimento deles e ainda estamos em fase de investiga\u00e7\u00e3o preliminar.<\/em><\/p>\n\n<p class=\"wp-block-paragraph\"><em>Foi no dia 11 de julho que uma amiga da jovem que j\u00e1 havia entrado em contato comigo, me deixou uma mensagem dizendo que tinha provas da rela\u00e7\u00e3o sexual de sua amiga com o padre Del Castillo.<\/em><\/p>\n\n<p class=\"wp-block-paragraph\"><em>Em 13 de julho, o padre Del Castillo pediu para se encontrar com o padre Bertrand Monnard, vig\u00e1rio geral, e reconheceu sua grave falta.<\/em><\/p>\n\n<p class=\"wp-block-paragraph\"><em>No dia 14 de julho, juntamente com o padre Trist\u00e1n P\u00e9rez, provincial do Instituto do Verbo Encarnado, tomamos a decis\u00e3o de remover o padre Del Castillo do cargo de p\u00e1roco de Jonzac e envi\u00e1-lo para uma comunidade do Instituto na It\u00e1lia. \u00c9 verdade que durante o ver\u00e3o ele foi ver sua fam\u00edlia no Peru, mas est\u00e1 prestes a voltar para a Europa.   <\/em><\/p>\n\n<p class=\"wp-block-paragraph\"><em>Por outro lado, depois que os pais da jovem v\u00edtima entraram em contato com a diocese, encontrei-me com eles em 13 de agosto.<\/em><\/p>\n\n<p class=\"wp-block-paragraph\"><em>Na fase atual, a diocese de La Rochelle e o Instituto do Verbo Encarnado, est\u00e3o em processo de completar o expediente do Padre Del Castillo antes de iniciar os procedimentos eclesiais e, se necess\u00e1rio, civis.<\/em><\/p>\n\n<p class=\"wp-block-paragraph\"><em>Todos n\u00f3s somos afetados por esta trag\u00e9dia. Temos uma forte vontade de fazer a verdade e um desejo de justi\u00e7a, sabendo que ela est\u00e1 nas m\u00e3os de Deus.   <\/em><\/p>\n\n<p class=\"wp-block-paragraph\"><strong><em>Arcebispo Fran\u00e7ois Jacolin<\/em><\/strong><\/p>\n\n<p class=\"wp-block-paragraph\"><em>Bispo de Lu\u00e7on<br\/>e administrador apost\u00f3lico da diocese de La Rochelle<\/em><\/p>\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A diocese de La Rochelle (no departamento de Charente-Maritime, Fran\u00e7a) cedeu \u00e0 press\u00e3o da m\u00eddia e finalmente emitiu uma declara\u00e7\u00e3o oficial sobre o padre Anthony del Castillo, mais de um m\u00eas ap\u00f3s nossa publica\u00e7\u00e3o! Por outro lado, para ter uma publica\u00e7\u00e3o oficial do Instituto do Verbo Encarnado, teremos que esperar, e esperar, e esperar&#8230; O [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":6182,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"jetpack_seo_schema_type":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[61],"tags":[219],"class_list":["post-6200","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-dos-administradores","tag-bispo"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/verbo-encarnado-ssvm-abusos.info\/wp-content\/uploads\/2025\/08\/Screenshot-2025-08-21-175912.png?fit=758%2C358&ssl=1","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/verbo-encarnado-ssvm-abusos.info\/pt-br\/wp-json\/wp\/v2\/posts\/6200","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/verbo-encarnado-ssvm-abusos.info\/pt-br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/verbo-encarnado-ssvm-abusos.info\/pt-br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/verbo-encarnado-ssvm-abusos.info\/pt-br\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/verbo-encarnado-ssvm-abusos.info\/pt-br\/wp-json\/wp\/v2\/comments?post=6200"}],"version-history":[{"count":1,"href":"https:\/\/verbo-encarnado-ssvm-abusos.info\/pt-br\/wp-json\/wp\/v2\/posts\/6200\/revisions"}],"predecessor-version":[{"id":6201,"href":"https:\/\/verbo-encarnado-ssvm-abusos.info\/pt-br\/wp-json\/wp\/v2\/posts\/6200\/revisions\/6201"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/verbo-encarnado-ssvm-abusos.info\/pt-br\/wp-json\/wp\/v2\/media\/6182"}],"wp:attachment":[{"href":"https:\/\/verbo-encarnado-ssvm-abusos.info\/pt-br\/wp-json\/wp\/v2\/media?parent=6200"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/verbo-encarnado-ssvm-abusos.info\/pt-br\/wp-json\/wp\/v2\/categories?post=6200"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/verbo-encarnado-ssvm-abusos.info\/pt-br\/wp-json\/wp\/v2\/tags?post=6200"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}